{"id":19172,"date":"2025-01-13T00:59:02","date_gmt":"2025-01-13T08:59:02","guid":{"rendered":"https:\/\/internetaddictsanonymous.org\/?page_id=19172"},"modified":"2025-04-19T07:12:22","modified_gmt":"2025-04-19T14:12:22","slug":"sinais-de-vicio-em-facebook","status":"publish","type":"page","link":"https:\/\/internetaddictsanonymous.org\/pt\/internet-and-technology-addiction\/social-media-addiction\/signs-of-facebook-addiction\/","title":{"rendered":"Sinais de V\u00edcio em Facebook"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Bem-vindo \u00e0 Internet e Viciados em Tecnologia An\u00f4nimos! Estamos felizes por nos ter encontrado e esperamos que nossa comunidade possa ser t\u00e3o \u00fatil para voc\u00ea quanto tem sido para n\u00f3s.&nbsp;<strong>ITAA \u00e9 uma bolsa de doze passos de indiv\u00edduos que se ap\u00f3iam mutuamente na recupera\u00e7\u00e3o do v\u00edcio da internet e da tecnologia.<\/strong>&nbsp;Isso inclui v\u00edcio em m\u00eddias sociais, v\u00edcio em telefone, v\u00edcio em v\u00eddeo, v\u00edcio em televis\u00e3o, v\u00edcio em jogos, v\u00edcio em not\u00edcias, v\u00edcio em pornografia, aplicativos de namoro, pesquisa on-line, compras on-line ou qualquer outra atividade digital que se torne compulsiva e problem\u00e1tica.&nbsp;<\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-left is-layout-flex wp-container-core-buttons-is-layout-63375db1 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-width wp-block-button__width-50 is-style-fill\"><a class=\"wp-block-button__link has-white-color has-blue-background-color has-text-color has-background has-custom-font-size wp-element-button\" href=\"https:\/\/internetaddictsanonymous.org\/pt\/reunioes-on-line\/\" style=\"border-radius:100px;font-size:25px;font-style:normal;font-weight:900\">Participe de uma reuni\u00e3o<\/a><\/div>\n\n\n<\/div>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Independentemente da dimens\u00e3o do seu problema, encorajamos voc\u00ea a participar de uma de nossas reuni\u00f5es di\u00e1rias para verificar se a ITAA pode ajud\u00e1-lo(a). Nossas reuni\u00f5es s\u00e3o gratuitas e abertas a qualquer pessoa que tenha dificuldades com o uso compulsivo da internet. As reuni\u00f5es s\u00e3o seguras, protegidas e an\u00f4nimas. A ITAA \u00e9 extremamente diversa e nossas reuni\u00f5es incluem membros de todas as idades, g\u00eaneros e etnias do mundo todo. Al\u00e9m disso, tamb\u00e9m realizamos reuni\u00f5es em [localiza\u00e7\u00e3o n\u00e3o especificada].&nbsp;<a href=\"https:\/\/internetaddictsanonymous.org\/fr\/itaa-en-francais\/\">Franc\u00eas<\/a>,&nbsp;<a href=\"https:\/\/internetaddictsanonymous.org\/es\/espanol\/\">Espanhol<\/a>,&nbsp;<a href=\"https:\/\/internetaddictsanonymous.org\/ru\/itaa-%d0%bd%d0%b0-%d1%80%d1%83%d1%81%d1%81%d0%ba%d0%be%d0%bc-%d1%8f%d0%b7%d1%8b%d0%ba%d0%b5\/\">Russo<\/a>,&nbsp;<a href=\"https:\/\/internetaddictsanonymous.org\/de\/itaa-in-german\/\">Alem\u00e3o<\/a>,&nbsp;<a href=\"https:\/\/internetaddictsanonymous.org\/nl\/lokale-internet-verslavingsbijeenkomsten\/nederland-amsterdam\/\">Holand\u00eas<\/a>,&nbsp;<a href=\"https:\/\/internetaddictsanonymous.org\/he\/%d7%90%d7%99%d7%98%d7%90-%d7%91%d7%a2%d7%91%d7%a8%d7%99%d7%aa\/\">Hebraico<\/a>,&nbsp;<a href=\"https:\/\/internetaddictsanonymous.org\/ar\/itaa-%d8%a8%d8%a7%d9%84%d9%84%d8%ba%d8%a9-%d8%a7%d9%84%d8%b9%d8%b1%d8%a8%d9%8a%d8%a9\/\">\u00e1rabe<\/a>e&nbsp;<a href=\"https:\/\/internetaddictsanonymous.org\/pl\/itaa-in-polish\/\">Polon\u00eas<\/a>. Voc\u00ea tamb\u00e9m pode encontrar uma reuni\u00e3o local, presencial em&nbsp;<a href=\"https:\/\/internetaddictsanonymous.org\/pt\/local-internet-addiction-meetings\/\">sua cidade<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">O que \u00e9 o v\u00edcio em Facebook?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">O v\u00edcio em Facebook \u00e9 o uso compulsivo e prejudicial da plataforma Meta, levando \u00e0 incapacidade de controlar o tempo gasto no aplicativo ou site. Pode envolver rolagem excessiva pelo feed de not\u00edcias, verifica\u00e7\u00e3o constante de notifica\u00e7\u00f5es, intera\u00e7\u00e3o obsessiva com publica\u00e7\u00f5es, fotos e v\u00eddeos, ou participa\u00e7\u00e3o em discuss\u00f5es e coment\u00e1rios intermin\u00e1veis. Usu\u00e1rios do Facebook podem sentir-se compelidos a atualizar seu status, realizar compara\u00e7\u00f5es sociais excessivas ou buscar valida\u00e7\u00e3o por meio de curtidas e coment\u00e1rios. Esse comportamento pode perturbar a rotina di\u00e1ria, afetar a sa\u00fade mental e causar neglig\u00eancia de responsabilidades, relacionamentos e bem-estar pessoal na vida real. Como um subconjunto de<a href=\"https:\/\/internetaddictsanonymous.org\/pt\/vicio-na-internet\/\"> depend\u00eancia de internet e tecnologia<\/a>, O v\u00edcio em Facebook pode levar a altera\u00e7\u00f5es cerebrais que, com o tempo, comprometem nossa capacidade de concentra\u00e7\u00e3o, prioriza\u00e7\u00e3o, regula\u00e7\u00e3o do humor e relacionamento com os outros.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aqueles de n\u00f3s que se identificam como viciados em Facebook vivenciaram diversos sintomas comuns. Us\u00e1vamos o Facebook por mais tempo do que pretend\u00edamos, apesar das tentativas de controlar ou reduzir o uso. Mesmo cientes das consequ\u00eancias e com vontade de parar, n\u00e3o consegu\u00edamos. Quando desconectados do Facebook, sent\u00edamos distra\u00e7\u00e3o, ansiedade e irritabilidade. \u00c9ramos incapazes de aproveitar e estar presentes em nossas vidas offline. Us\u00e1vamos o Facebook para alterar nosso humor e escapar dos nossos problemas. Nossos comportamentos viciantes comprometiam nossas intera\u00e7\u00f5es sociais, nossos estudos e nossas oportunidades de carreira. Sent\u00edamos vergonha e desmoraliza\u00e7\u00e3o pelo uso excessivo do Facebook.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quando come\u00e7amos a perceber essas experi\u00eancias preocupantes, reconhecemos que algo n\u00e3o estava certo. Mas muitos de n\u00f3s ainda question\u00e1vamos se realmente t\u00ednhamos um v\u00edcio. Para aqueles que ainda t\u00eam d\u00favidas, as perguntas a seguir podem ajudar a identificar melhor os sinais de depend\u00eancia em suas vidas.<br><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Question\u00e1rio de depend\u00eancia do Facebook:<\/strong><\/h2>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Alguma vez entro no Facebook para dar uma olhadinha r\u00e1pida em alguma coisa e depois percebo que horas se passaram?<\/li>\n\n\n\n<li>Ser\u00e1 que alguma vez estabele\u00e7o limites para o meu uso do Facebook, apenas para quebrar os meus compromissos?<\/li>\n\n\n\n<li>Tenho sess\u00f5es no Facebook que duram o dia todo ou se estendem at\u00e9 tarde da noite?<\/li>\n\n\n\n<li>Recorro ao Facebook sempre que tenho um momento livre?<\/li>\n\n\n\n<li>Passar tempo no Facebook me leva a negligenciar minha higiene pessoal, nutri\u00e7\u00e3o ou sa\u00fade f\u00edsica?<\/li>\n\n\n\n<li>Eu me sinto isolado, emocionalmente distante, distra\u00eddo ou ansioso quando n\u00e3o estou no Facebook?<\/li>\n\n\n\n<li>O meu uso do Facebook causa conflitos ou afastamento nos meus relacionamentos pessoais?<\/li>\n\n\n\n<li>Meus h\u00e1bitos no Facebook prejudicaram meus estudos, minhas finan\u00e7as ou minha carreira?<\/li>\n\n\n\n<li>Ser\u00e1 que escondo ou minto sobre quanto tempo passo no Facebook ou sobre o tipo de conte\u00fado que consulto?<\/li>\n\n\n\n<li>Sinto culpa ou vergonha pelo meu uso do Facebook?<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">Ningu\u00e9m deveria sofrer por causa do uso do Facebook. Se voc\u00ea respondeu sim a v\u00e1rias das perguntas acima, recomendamos que considere buscar ajuda.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-left is-layout-flex wp-container-core-buttons-is-layout-63375db1 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-width wp-block-button__width-50 is-style-fill\"><a class=\"wp-block-button__link has-white-color has-blue-background-color has-text-color has-background has-custom-font-size wp-element-button\" href=\"https:\/\/internetaddictsanonymous.org\/pt\/reunioes-on-line\/\" style=\"border-radius:100px;font-size:25px;font-style:normal;font-weight:900\">Participe de uma reuni\u00e3o<\/a><\/div>\n\n\n<\/div>\n\n\n\n<div style=\"height:75px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Quais s\u00e3o os efeitos do v\u00edcio em Facebook?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">O v\u00edcio em Facebook e outros v\u00edcios em redes sociais s\u00e3o um subconjunto do transtorno de depend\u00eancia da internet (TDI), que foi investigado pela primeira vez pela psic\u00f3loga Dra. Kimberly S. Young, que publicou o estudo original.<a href=\"https:\/\/psycnet.apa.org\/record\/2000-16534-005\"> crit\u00e9rios de diagn\u00f3stico<\/a> para esse transtorno de sa\u00fade mental em 1998. Atualmente, ainda h\u00e1 uma discuss\u00e3o aberta na comunidade cient\u00edfica sobre como definir, qualificar e estudar as v\u00e1rias formas de transtorno de depend\u00eancia da Internet, e o Manual Diagn\u00f3stico e Estat\u00edstico de Transtornos Mentais (DSM-5-TR) da Associa\u00e7\u00e3o Americana de Psiquiatria come\u00e7ou a reconhecer a gravidade dessa classe de v\u00edcios por meio da inclus\u00e3o de<a href=\"https:\/\/www.psychiatry.org\/patients-families\/internet-gaming\"> transtorno de jogos na internet<\/a>. H\u00e1<a href=\"https:\/\/internetaddictsanonymous.org\/pt\/the-doctors-opinion\/\"> consenso generalizado<\/a> de pesquisadores e cl\u00ednicos que o uso excessivo, problem\u00e1tico e compulsivo da Internet, da m\u00eddia digital e de dispositivos inteligentes vem aumentando nas \u00faltimas duas d\u00e9cadas e que a preval\u00eancia desse v\u00edcio comportamental est\u00e1 associada a uma variedade de problemas mentais, emocionais, f\u00edsicos, interpessoais e profissionais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Talvez o mais significativo seja o fato de que as libera\u00e7\u00f5es de dopamina desencadeadas pelo v\u00edcio em internet e tecnologia causam<a href=\"https:\/\/www.frontiersin.org\/articles\/10.3389\/fnhum.2014.00375\/full\"> mudan\u00e7as estruturais no c\u00e9rebro<\/a> muito semelhantes \u00e0s mudan\u00e7as ocorridas em<a href=\"https:\/\/onlinelibrary.wiley.com\/doi\/10.1111\/adb.12338\"> pessoas com depend\u00eancia de \u00e1lcool ou drogas<\/a>. Essas mudan\u00e7as levam a redu\u00e7\u00f5es em nossas<a href=\"https:\/\/www.nature.com\/articles\/s41598-018-19904-y\"> tomada de decis\u00f5es<\/a>,<a href=\"https:\/\/www.sciencedirect.com\/science\/article\/abs\/pii\/S0306460318302065?via%3Dihub\"> racioc\u00ednio<\/a>,<a href=\"https:\/\/www.nature.com\/articles\/s41380-021-01315-7.pdf?proof=t%2529\"> expectativa de recompensa<\/a>,<a href=\"https:\/\/www.nature.com\/articles\/s41380-021-01315-7.pdf?proof=t%2529\"> fun\u00e7\u00e3o executiva<\/a>,<a href=\"https:\/\/www.sciencedirect.com\/science\/article\/abs\/pii\/S0306460318302065?via%3Dihub\"> fun\u00e7\u00e3o cognitiva<\/a>,<a href=\"https:\/\/www.frontiersin.org\/articles\/10.3389\/fpsyg.2016.00597\/full\"> processamento emocional<\/a>e nosso<a href=\"https:\/\/journals.plos.org\/plosone\/article?id=10.1371\/journal.pone.0030253\"> mem\u00f3ria de trabalho<\/a>. Diversos estudos demonstraram que o acesso a<a href=\"https:\/\/journals.plos.org\/plosone\/article?id=10.1371\/journal.pone.0219115\"> televis\u00e3o e videogames<\/a> diminui\u00e7\u00f5es<a href=\"https:\/\/www.frontiersin.org\/articles\/10.3389\/fnhum.2019.00262\/full\"> a quantidade de medica\u00e7\u00e3o para dor<\/a> necess\u00e1rio por<a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pmc\/articles\/PMC2082989\/\"> pacientes hospitalares<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9 claro que os efeitos do v\u00edcio em internet e tecnologia n\u00e3o se refletem apenas na estrutura do nosso c\u00e9rebro, mas tamb\u00e9m em nosso cotidiano. O v\u00edcio em internet e tecnologia est\u00e1 fortemente correlacionado com<a href=\"https:\/\/www.frontiersin.org\/articles\/10.3389\/fpsyg.2016.00597\/full\"> transtorno de controle de impulsos<\/a>,<a href=\"https:\/\/www.oxfordclinicalpsych.com\/view\/10.1093\/med-psych\/9780199928163.001.0001\/med-9780199928163-chapter-28\"> Transtorno de d\u00e9ficit de aten\u00e7\u00e3o e hiperatividade (TDAH)<\/a>,<a href=\"https:\/\/www.sciencedirect.com\/science\/article\/pii\/S0747563222000231\"> ansiedade e neuroticismo<\/a>,<a href=\"https:\/\/www.oxfordclinicalpsych.com\/view\/10.1093\/med-psych\/9780199928163.001.0001\/med-9780199928163-chapter-28\"> aumento do uso de subst\u00e2ncias<\/a>e<a href=\"https:\/\/www.sciencedirect.com\/science\/article\/pii\/S0747563222000231\"> depress\u00e3o e baixa autoestima<\/a>. Al\u00e9m desses transtornos concomitantes, est\u00e1 associado a uma s\u00e9rie de problemas de sa\u00fade, como um risco maior de<a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/32451650\/\"> doen\u00e7a cardiometab\u00f3lica<\/a>,<a href=\"https:\/\/jcsm.aasm.org\/doi\/10.5664\/jcsm.6704\"> menor qualidade do sono<\/a>,<a href=\"https:\/\/jcsm.aasm.org\/doi\/10.5664\/jcsm.6704\"> aumento da fadiga<\/a>e<a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/24619594\/\"> sintomas de ins\u00f4nia<\/a>todos os quais s\u00e3o<a href=\"https:\/\/www.thelancet.com\/journals\/lancet\/article\/PIIS0140-6736(16)30175-1\/fulltext#seccestitle120\"> correlacionados<\/a> para um<a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pmc\/articles\/PMC2938855\/\"> maior taxa de mortalidade<\/a>. Talvez o mais tr\u00e1gico de tudo seja que indiv\u00edduos com depend\u00eancia de internet e tecnologia t\u00eam taxas muito mais altas de idea\u00e7\u00e3o, planejamento e tentativas de suic\u00eddio.<a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/29877640\/\">cerca de tr\u00eas vezes a m\u00e9dia<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Essas descobertas s\u00e3o motivo de grande preocupa\u00e7\u00e3o. Embora alguns possam minimizar o impacto do v\u00edcio em Internet e tecnologia em compara\u00e7\u00e3o com subst\u00e2ncias qu\u00edmicas, a verdade \u00e9 que o v\u00edcio em Internet e tecnologia altera nosso c\u00e9rebro de maneira semelhante aos efeitos produzidos pelo v\u00edcio em \u00e1lcool, hero\u00edna ou outras drogas.<br><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Quem corre o risco de desenvolver depend\u00eancia do Facebook?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">O uso compulsivo do Facebook \u00e9 uma condi\u00e7\u00e3o que pode afetar pessoas de uma ampla gama de perfis demogr\u00e1ficos, incluindo adolescentes e adultos mais velhos. Nossos encontros re\u00fanem jovens adultos, estudantes universit\u00e1rios, profissionais, pais e aposentados, com membros de todas as idades, g\u00eaneros e etnias do mundo todo. Embora os fatores de risco sejam variados, o v\u00edcio em internet e o uso problem\u00e1tico do Facebook n\u00e3o discriminam com base em idade, n\u00edvel de escolaridade, condi\u00e7\u00e3o socioecon\u00f4mica, tra\u00e7os de personalidade como introvers\u00e3o ou extrovers\u00e3o, localiza\u00e7\u00e3o geogr\u00e1fica, ra\u00e7a ou etnia. Seus efeitos negativos impactam n\u00e3o apenas o pr\u00f3prio usu\u00e1rio, mas tamb\u00e9m seus familiares e amigos.<a href=\"https:\/\/internetaddictsanonymous.org\/pt\/para-familia-e-amigos\/\"> seus familiares e amigos<\/a>. Ao prejudicar nosso potencial, autoestima e satisfa\u00e7\u00e3o com a vida, o uso excessivo do Facebook pode afetar negativamente nossas vidas. Al\u00e9m disso, ao contribuir para a depress\u00e3o e tend\u00eancias suicidas, nosso v\u00edcio pode ser fatal. Independentemente de nossa origem, se o uso do Facebook est\u00e1 nos causando sofrimento ou dificuldades, existem medidas que podemos tomar para melhorar nossa situa\u00e7\u00e3o e encontrar al\u00edvio.<br><br><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Uma solu\u00e7\u00e3o para o v\u00edcio em Facebook<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Embora o v\u00edcio em Internet e tecnologia s\u00f3 tenha come\u00e7ado a receber aten\u00e7\u00e3o nos \u00faltimos anos, a doen\u00e7a do v\u00edcio n\u00e3o \u00e9 nova. Milh\u00f5es de pessoas encontraram a liberdade sustent\u00e1vel e de longo prazo de seus comportamentos viciantes por meio de grupos de apoio de ajuda m\u00fatua, segundo o modelo dos Alco\u00f3licos An\u00f4nimos. Um estudo recente<a href=\"https:\/\/www.nytimes.com\/2020\/03\/11\/upshot\/alcoholics-anonymous-new-evidence.html\"> revis\u00e3o sistem\u00e1tica<\/a> Um estudo conduzido por pesquisadores de sa\u00fade p\u00fablica de Stanford determinou que a participa\u00e7\u00e3o nos Alco\u00f3licos An\u00f4nimos (AA) quase sempre se mostrou mais eficaz do que outras terapias para alcan\u00e7ar a abstin\u00eancia cont\u00ednua do alcoolismo. O modelo dos AA foi adaptado com sucesso para ajudar pessoas que sofrem de diversos v\u00edcios, incluindo narc\u00f3ticos, maconha, nicotina, sexo, pornografia e comida, entre outros. Dando continuidade a essa tradi\u00e7\u00e3o, o grupo Viciados em Internet e Tecnologia An\u00f4nimos aplica o modelo comprovado dos AA para ajudar aqueles que sofrem de v\u00edcio em Facebook a encontrar a liberdade a longo prazo de seus comportamentos autodestrutivos. Compartilhamos nossa experi\u00eancia, for\u00e7a e esperan\u00e7a uns com os outros atrav\u00e9s de<a href=\"https:\/\/internetaddictsanonymous.org\/pt\/reunioes-on-line\/\"> reuni\u00f5es de grupo<\/a> e<a href=\"https:\/\/internetaddictsanonymous.org\/pt\/a-guide-to-outreach-calls-in-itaa\/\"> relacionamentos individuais<\/a>e trabalhamos com um programa de recupera\u00e7\u00e3o baseado nos Doze Passos dos Alco\u00f3licos An\u00f4nimos. Nossas reuni\u00f5es s\u00e3o gratuitas e an\u00f4nimas, e convidamos qualquer pessoa que ache que pode se beneficiar de apoio a visitar uma de nossas reuni\u00f5es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><br><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Como se recuperar do v\u00edcio em Facebook<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Existem a\u00e7\u00f5es concretas que podemos tomar para nos recuperarmos de nossos comportamentos compulsivos e restaurarmos nosso bem-estar emocional e mental. Descobrimos que as seguintes a\u00e7\u00f5es s\u00e3o de grande ajuda para alcan\u00e7armos uma liberdade duradoura e sustent\u00e1vel do uso compulsivo e problem\u00e1tico do Facebook.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>Participar de reuni\u00f5es di\u00e1rias<\/strong>. Al\u00e9m de um n\u00famero crescente de<a href=\"https:\/\/internetaddictsanonymous.org\/pt\/local-internet-addiction-meetings\/\"> reuni\u00f5es presenciais<\/a> em todo o mundo, a ITAA tem<a href=\"https:\/\/internetaddictsanonymous.org\/pt\/phone-online-meetings\/\"> reuni\u00f5es di\u00e1rias on-line<\/a> onde nossa irmandade global se re\u00fane para compartilhar experi\u00eancias, for\u00e7a e esperan\u00e7a uns com os outros. Somos incentivados a tentar participar de seis reuni\u00f5es em um curto espa\u00e7o de tempo para ajudar a decidir se a ITAA pode ser \u00fatil para n\u00f3s.<\/li>\n\n\n\n<li><strong>Fa\u00e7a liga\u00e7\u00f5es di\u00e1rias. <\/strong>Nossa depend\u00eancia do Facebook nos levou ao isolamento e \u00e0 autossufici\u00eancia. \u00c0 medida que come\u00e7amos a nos recuperar, aprendemos que podemos confiar nos outros e ser vulner\u00e1veis.<a href=\"https:\/\/internetaddictsanonymous.org\/pt\/a-guide-to-outreach-calls-in-itaa\/\"> Chamando outros membros<\/a> fora das reuni\u00f5es nos ajuda a permanecer conectados, apoiados e s\u00f3brios, al\u00e9m de nos dar a oportunidade de compartilhar mais detalhes do que durante uma reuni\u00e3o.<\/li>\n\n\n\n<li><strong>Absten\u00e7\u00e3o<\/strong>. Com a ajuda de outros membros em recupera\u00e7\u00e3o, n\u00f3s<a href=\"https:\/\/internetaddictsanonymous.org\/pt\/descoberta-sobriedade-folha-de-trabalho-uma-introducao-para-internet-recuperacao-de-vicios\/\"> identificar e se abster<\/a> dos comportamentos aditivos espec\u00edficos que est\u00e3o causando as maiores dificuldades em nossas vidas. Reconhecemos que esse \u00e9 um processo que se desenvolve ao longo do tempo e utilizamos o apoio dispon\u00edvel na ITAA para permanecermos s\u00f3brios um dia de cada vez.<\/li>\n\n\n\n<li><strong>Saiba mais sobre o processo de recupera\u00e7\u00e3o<\/strong>. Nosso site tem muitos<a href=\"https:\/\/internetaddictsanonymous.org\/pt\/recursos\/\"> Recursos<\/a> sobre a natureza de nosso v\u00edcio e como podemos melhor<a href=\"https:\/\/internetaddictsanonymous.org\/pt\/descoberta-sobriedade-folha-de-trabalho-uma-introducao-para-internet-recuperacao-de-vicios\/\"> tra\u00e7ar nossa jornada de recupera\u00e7\u00e3o<\/a>,<a href=\"https:\/\/internetaddictsanonymous.org\/pt\/a-guide-to-withdrawals\/\"> navegar pelos sintomas de abstin\u00eancia<\/a>e<a href=\"https:\/\/internetaddictsanonymous.org\/pt\/recursos\/ferramentas-de-recuperacao\/\"> responder aos desejos<\/a>. Al\u00e9m disso, h\u00e1 um rico acervo de literatura de outros programas de 12 Passos em que podemos nos apoiar para informar melhor nosso processo de cura e aprender mais sobre os m\u00e9todos testados pelo tempo que ajudaram milh\u00f5es de outros adictos a se recuperar.<\/li>\n\n\n\n<li><strong>Encontre um padrinho e trabalhe os Doze Passos. <\/strong>N\u00f3s nos beneficiamos ao pedir a algu\u00e9m com quem nos identificamos para<a href=\"https:\/\/internetaddictsanonymous.org\/pt\/patrocinio\/\"> patrocine-nos<\/a> e trabalhando<a href=\"https:\/\/internetaddictsanonymous.org\/pt\/12-passos-daitaa\/\"> Os Doze Passos<\/a> Junto com eles, que \u00e9 a base vital e transformadora de nossa recupera\u00e7\u00e3o de longo prazo do v\u00edcio. Uma \u00f3tima maneira de se conectar com poss\u00edveis padrinhos \u00e9 fazer liga\u00e7\u00f5es de contato com outros membros que estejam s\u00f3brios e trabalhando os Passos.<\/li>\n\n\n\n<li><strong>Utilize ajuda externa.<\/strong> Muitos membros complementam sua recupera\u00e7\u00e3o com uma variedade de recursos al\u00e9m da ITAA, tais como terapia cognitivo-comportamental (TCC), psicoterapia, terapia de grupo, psiquiatria, centros de tratamento de depend\u00eancia em regime de interna\u00e7\u00e3o ou ambulatorial, outras irmandades de 12 Passos, aconselhamento espiritual ou outros recursos de bem-estar de sa\u00fade mental. Embora n\u00e3o endossemos nenhuma op\u00e7\u00e3o de tratamento ou interven\u00e7\u00e3o em particular, incentivamos todos os membros a se valerem de qualquer ajuda externa que possa apoi\u00e1-los em sua jornada de recupera\u00e7\u00e3o. Um profissional de sa\u00fade mental ou da \u00e1rea de sa\u00fade pode dar conselhos adaptados \u00e0 sua situa\u00e7\u00e3o.<\/li>\n<\/ol>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Como \u00e9 a sobriedade ap\u00f3s um per\u00edodo de v\u00edcio em Facebook?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A sobriedade na ITAA \u00e9 um processo de descoberta que parece diferente para cada um de n\u00f3s. Como parte desse processo, n\u00f3s<a href=\"https:\/\/internetaddictsanonymous.org\/pt\/descoberta-sobriedade-folha-de-trabalho-uma-introducao-para-internet-recuperacao-de-vicios\/\"> identificar e se abster<\/a> a partir dos comportamentos espec\u00edficos que desencadeiam nosso v\u00edcio. Tamb\u00e9m descobrimos que \u00e9 ben\u00e9fico estabelecer uma vis\u00e3o positiva para o uso da internet e da tecnologia. Por exemplo, podemos praticar o uso da tecnologia de forma intencional, m\u00ednima ou apenas quando necess\u00e1rio. Alguns de n\u00f3s tamb\u00e9m acharam \u00fatil parar de usar completamente e excluir nossas contas do Facebook, evitar outras plataformas de conte\u00fado baseadas em algoritmos, fazer uma desintoxica\u00e7\u00e3o digital completa de todo entretenimento online por um per\u00edodo de tempo, priorizar atividades no mundo real, cultivar relacionamentos na vida real e participar de reuni\u00f5es do ITAA para ajudar a diminuir nosso v\u00edcio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Respeitamos a dignidade de cada membro em descobrir seu pr\u00f3prio caminho para a recupera\u00e7\u00e3o e trabalhamos com outros membros experientes para ajudar a definir o que a sobriedade significa para cada um de n\u00f3s individualmente. Como parte desse processo, contamos com reuni\u00f5es e telefonemas para nos ajudar a manter nossos compromissos com a sobriedade. Em vez de usar telas para nos distrair ou anestesiar nossas emo\u00e7\u00f5es, buscamos usar a tecnologia como uma ferramenta para alcan\u00e7ar nossos objetivos, viver em conson\u00e2ncia com nossos valores e desenvolver vidas plenas.<br><br><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Tipos de depend\u00eancia da Internet<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Embora todos n\u00f3s soframos de uma doen\u00e7a comum, ela se expressa de maneiras diferentes para cada um de n\u00f3s. A seguir, apresentamos alguns comportamentos compulsivos comuns em rela\u00e7\u00e3o \u00e0 Internet e \u00e0 tecnologia. \u00c9 importante ter em mente que essa lista n\u00e3o \u00e9 abrangente nem prescritiva - \u00e9 essencial identificar nossos pr\u00f3prios comportamentos pessoais compulsivos ou desnecess\u00e1rios em rela\u00e7\u00e3o \u00e0 Internet e \u00e0 tecnologia com a ajuda de outros membros.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/internetaddictsanonymous.org\/pt\/vicio-na-internet\/vicio-das-midias-sociais\/\"><strong>V\u00edcio em m\u00eddia social<\/strong><\/a> \u00c9 o uso compulsivo de plataformas de m\u00eddia social, redes sociais, aplicativos de mensagens, feeds de not\u00edcias, f\u00f3runs de discuss\u00e3o, salas de bate-papo e comunidades online. O uso compulsivo de m\u00eddias sociais pode incluir <a href=\"https:\/\/internetaddictsanonymous.org\/pt\/dependencia-de-internet-e-tecnologia\/vicio-das-midias-sociais\/sinais-de-vicio-em-facebook\/\">Facebook<\/a>, <a href=\"https:\/\/internetaddictsanonymous.org\/pt\/dependencia-de-internet-e-tecnologia\/vicio-das-midias-sociais\/sinais-de-vicio-no-instagram\/\">Instagram<\/a>, <a href=\"https:\/\/internetaddictsanonymous.org\/pt\/dependencia-de-internet-e-tecnologia\/vicio-das-midias-sociais\/sinais-de-vicio-em-twitter-x-vicio\/\">Twitter<\/a>, <a href=\"https:\/\/internetaddictsanonymous.org\/pt\/dependencia-de-internet-e-tecnologia\/vicio-das-midias-sociais\/dependencia-de-tiktok\/\">TikTok<\/a>, Snapchat, Discord, <a href=\"https:\/\/internetaddictsanonymous.org\/pt\/dependencia-de-internet-e-tecnologia\/vicio-das-midias-sociais\/recuperando-se-do-vicio-em-reddit-2\/\">Reddit<\/a>, <a href=\"https:\/\/internetaddictsanonymous.org\/pt\/dependencia-de-internet-e-tecnologia\/vicio-das-midias-sociais\/sinais-de-vicio-no-pinterest\/\">Pinterest<\/a>, e outros.<\/li>\n\n\n\n<li><a href=\"https:\/\/internetaddictsanonymous.org\/pt\/vicio-na-internet\/vicio-de-streaming\/\"><strong>Adic\u00e7\u00e3o em v\u00eddeos online<\/strong><\/a> \u00e9 o uso compulsivo e viciante de qualquer plataforma ou conte\u00fado de streaming. Isso inclui v\u00eddeos online, filmes, televis\u00e3o, podcasts e plataformas como <a href=\"https:\/\/internetaddictsanonymous.org\/pt\/dependencia-de-internet-e-tecnologia\/vicio-de-streaming\/youtube-addiction\/\">YouTube<\/a>, Netflix, Amazon Prime, <a href=\"https:\/\/internetaddictsanonymous.org\/pt\/dependencia-de-internet-e-tecnologia\/vicio-de-streaming\/vicio-em-witch\/\">Contra\u00e7\u00e3o muscular<\/a>ou <a href=\"https:\/\/internetaddictsanonymous.org\/pt\/dependencia-de-internet-e-tecnologia\/vicio-das-midias-sociais\/dependencia-de-tiktok\/\">TikTok<\/a>.<\/li>\n\n\n\n<li><a href=\"https:\/\/internetaddictsanonymous.org\/pt\/vicio-em-tecnologia\/smartphone-addiction\/\"><strong>V\u00edcio em telefone<\/strong><\/a> \u00e9 o uso compulsivo e autodestrutivo de dispositivos e aplicativos de smartphones. Isso pode envolver o uso excessivo do telefone ou a verifica\u00e7\u00e3o compulsiva de notifica\u00e7\u00f5es, especialmente em hor\u00e1rios inadequados, como tarde da noite ou enquanto estuda, trabalha ou dirige.<\/li>\n\n\n\n<li><strong><a href=\"https:\/\/internetaddictsanonymous.org\/pt\/dependencia-de-internet-e-tecnologia\/vicio-em-videogame\/\">V\u00edcio em videogame<\/a><\/strong> refere-se ao uso obsessivo, insalubre ou excessivo de videogames, bem como de quaisquer outros jogos digitais ou on-line. Isso inclui jogos de computador, jogos de console, jogos de telefone e jogos de m\u00eddia social.\u00a0<\/li>\n\n\n\n<li><strong><a href=\"https:\/\/internetaddictsanonymous.org\/pt\/viciados-em-internet-e-tecnologia-anonimos\/vicio-em-pornografia\/\">V\u00edcio em pornografia<\/a><\/strong> \u00e9 o consumo viciante de conte\u00fado er\u00f3tico digital e tamb\u00e9m pode envolver outros comportamentos sexuais digitais prejudiciais \u00e0 sa\u00fade. Isso pode incluir v\u00eddeos, imagens ou textos pornogr\u00e1ficos, imagens sexualmente excitantes, salas de bate-papo an\u00f4nimas e aplicativos de namoro.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong><a href=\"https:\/\/internetaddictsanonymous.org\/pt\/dependencia-de-internet-e-tecnologia\/vicio-em-informacoes\/\">V\u00edcio em informa\u00e7\u00f5es<\/a> <\/strong>\u00e9 uma rela\u00e7\u00e3o viciante e doentia com a pesquisa e o consumo de informa\u00e7\u00f5es. Isso pode incluir o v\u00edcio em not\u00edcias, a rolagem de feeds de m\u00eddia social, compras on-line, enciclop\u00e9dias on-line e pesquisas on-line compulsivas, como pesquisas sobre produtos ou sa\u00fade.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Sobre a ITAA<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Internet and Technology Addicts Anonymous (Viciados em Internet e Tecnologia An\u00f4nimos) \u00e9 uma irmandade de Doze Passos baseada nos princ\u00edpios pioneiros de Alco\u00f3licos An\u00f4nimos. Nossa organiza\u00e7\u00e3o \u00e9 totalmente volunt\u00e1ria e autossustent\u00e1vel. O \u00fanico requisito para participar da ITAA \u00e9 o desejo de parar de usar a Internet e a tecnologia compulsivamente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">N\u00e3o temos opini\u00f5es sobre quest\u00f5es externas e n\u00e3o condenamos nem toleramos nenhuma tecnologia espec\u00edfica. N\u00e3o somos afiliados a nenhuma agenda pol\u00edtica, movimento religioso ou interesses externos. Nosso \u00fanico objetivo \u00e9 nos abstermos do uso compulsivo da Internet e da tecnologia e ajudar outras pessoas a se libertarem desse v\u00edcio. A ITAA \u00e9 uma organiza\u00e7\u00e3o norte-americana 501(c)(3), sem fins lucrativos e isenta de impostos federais, constitu\u00edda no estado do Colorado.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-left is-layout-flex wp-container-core-buttons-is-layout-63375db1 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-width wp-block-button__width-50 is-style-fill\"><a class=\"wp-block-button__link has-white-color has-blue-background-color has-text-color has-background has-custom-font-size wp-element-button\" href=\"https:\/\/internetaddictsanonymous.org\/pt\/reunioes-on-line\/\" style=\"border-radius:100px;font-size:25px;font-style:normal;font-weight:900\">Participe de uma reuni\u00e3o<\/a><\/div>\n\n\n<\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<!-- PMB print buttons is only displayed on a single post\/page URLs-->","protected":false},"excerpt":{"rendered":"<p>Bem-vindo(a) ao Viciados em Internet e Tecnologia An\u00f4nimos! Ficamos felizes por voc\u00ea ter nos encontrado e esperamos que nossa comunidade possa ser t\u00e3o \u00fatil para voc\u00ea quanto tem sido para n\u00f3s. O ITAA \u00e9 uma irmandade de Doze Passos formada por indiv\u00edduos que se apoiam mutuamente na recupera\u00e7\u00e3o do v\u00edcio em internet e tecnologia. Isso inclui v\u00edcio em redes sociais, v\u00edcio em celular, v\u00edcio em v\u00eddeo, v\u00edcio em televis\u00e3o\u2026 <a href=\"https:\/\/internetaddictsanonymous.org\/pt\/internet-and-technology-addiction\/social-media-addiction\/signs-of-facebook-addiction\/\" class=\"more-link\">Continue lendo <span class=\"screen-reader-text\">Sinais de V\u00edcio em Facebook<\/span><\/a><\/p>","protected":false},"author":35194289,"featured_media":0,"parent":4446,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"full-width-page.php","meta":{"inline_featured_image":false,"_lmt_disableupdate":"","_lmt_disable":"","_wpcom_ai_launchpad_about_page":false,"_wpcom_ai_launchpad_gallery_page":false,"_wpcom_ai_launchpad_contact_page":false,"_wpcom_ai_launchpad_events_page":false,"_wpcom_ai_launchpad_video_page":false,"_wpcom_ai_launchpad_portfolio_piece":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"tags":[],"class_list":["post-19172","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Signs of Facebook Addiction &#8211; Internet and Technology Addicts Anonymous<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/internetaddictsanonymous.org\/pt\/dependencia-de-internet-e-tecnologia\/vicio-das-midias-sociais\/sinais-de-vicio-em-facebook\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Signs of Facebook Addiction &#8211; Internet and Technology Addicts Anonymous\" \/>\n<meta property=\"og:description\" content=\"Welcome to Internet and Technology Addicts Anonymous! We\u2019re glad you\u2019ve found us, and we hope our community can be as helpful to you as it has been for us.&nbsp;ITAA is a Twelve-Step fellowship of individuals who support each other in recovering from internet and technology addiction.&nbsp;This includes social media addiction, phone addiction, video addiction, television &hellip; Continue lendo Signs of Facebook Addiction\" \/>\n<meta property=\"og:url\" content=\"https:\/\/internetaddictsanonymous.org\/pt\/dependencia-de-internet-e-tecnologia\/vicio-das-midias-sociais\/sinais-de-vicio-em-facebook\/\" \/>\n<meta property=\"og:site_name\" content=\"Internet and Technology Addicts Anonymous\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-19T14:12:22+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/internetaddictsanonymous.org\\\/internet-and-technology-addiction\\\/social-media-addiction\\\/signs-of-facebook-addiction\\\/\",\"url\":\"https:\\\/\\\/internetaddictsanonymous.org\\\/internet-and-technology-addiction\\\/social-media-addiction\\\/signs-of-facebook-addiction\\\/\",\"name\":\"Signs of Facebook Addiction &#8211; Internet and Technology Addicts Anonymous\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/internetaddictsanonymous.org\\\/#website\"},\"datePublished\":\"2025-01-13T08:59:02+00:00\",\"dateModified\":\"2025-04-19T14:12:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/internetaddictsanonymous.org\\\/internet-and-technology-addiction\\\/social-media-addiction\\\/signs-of-facebook-addiction\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/internetaddictsanonymous.org\\\/internet-and-technology-addiction\\\/social-media-addiction\\\/signs-of-facebook-addiction\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/internetaddictsanonymous.org\\\/internet-and-technology-addiction\\\/social-media-addiction\\\/signs-of-facebook-addiction\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/internetaddictsanonymous.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Signs of Internet and Technology Addiction\",\"item\":\"https:\\\/\\\/internetaddictsanonymous.org\\\/internet-and-technology-addiction\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Recovering from Social Media Addiction\",\"item\":\"https:\\\/\\\/internetaddictsanonymous.org\\\/internet-and-technology-addiction\\\/social-media-addiction\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Signs of Facebook Addiction\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/internetaddictsanonymous.org\\\/#website\",\"url\":\"https:\\\/\\\/internetaddictsanonymous.org\\\/\",\"name\":\"Internet and Technology Addicts Anonymous\",\"description\":\"Worldwide 12-step Fellowship for Internet and Technology Addiction\",\"publisher\":{\"@id\":\"https:\\\/\\\/internetaddictsanonymous.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/internetaddictsanonymous.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/internetaddictsanonymous.org\\\/#organization\",\"name\":\"Internet and Technology Addicts Anonymous\",\"url\":\"https:\\\/\\\/internetaddictsanonymous.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/internetaddictsanonymous.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/internetaddictsanonymous.org\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-ITAA-logo-480px.png\",\"contentUrl\":\"https:\\\/\\\/internetaddictsanonymous.org\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-ITAA-logo-480px.png\",\"width\":480,\"height\":480,\"caption\":\"Internet and Technology Addicts Anonymous\"},\"image\":{\"@id\":\"https:\\\/\\\/internetaddictsanonymous.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sinais de V\u00edcio em Facebook \u2013 Viciados em Internet e Tecnologia An\u00f4nimos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/internetaddictsanonymous.org\/pt\/dependencia-de-internet-e-tecnologia\/vicio-das-midias-sociais\/sinais-de-vicio-em-facebook\/","og_locale":"pt_BR","og_type":"article","og_title":"Signs of Facebook Addiction &#8211; Internet and Technology Addicts Anonymous","og_description":"Welcome to Internet and Technology Addicts Anonymous! We\u2019re glad you\u2019ve found us, and we hope our community can be as helpful to you as it has been for us.&nbsp;ITAA is a Twelve-Step fellowship of individuals who support each other in recovering from internet and technology addiction.&nbsp;This includes social media addiction, phone addiction, video addiction, television &hellip; Continue lendo Signs of Facebook Addiction","og_url":"https:\/\/internetaddictsanonymous.org\/pt\/dependencia-de-internet-e-tecnologia\/vicio-das-midias-sociais\/sinais-de-vicio-em-facebook\/","og_site_name":"Internet and Technology Addicts Anonymous","article_modified_time":"2025-04-19T14:12:22+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/internetaddictsanonymous.org\/internet-and-technology-addiction\/social-media-addiction\/signs-of-facebook-addiction\/","url":"https:\/\/internetaddictsanonymous.org\/internet-and-technology-addiction\/social-media-addiction\/signs-of-facebook-addiction\/","name":"Sinais de V\u00edcio em Facebook \u2013 Viciados em Internet e Tecnologia An\u00f4nimos","isPartOf":{"@id":"https:\/\/internetaddictsanonymous.org\/#website"},"datePublished":"2025-01-13T08:59:02+00:00","dateModified":"2025-04-19T14:12:22+00:00","breadcrumb":{"@id":"https:\/\/internetaddictsanonymous.org\/internet-and-technology-addiction\/social-media-addiction\/signs-of-facebook-addiction\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/internetaddictsanonymous.org\/internet-and-technology-addiction\/social-media-addiction\/signs-of-facebook-addiction\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/internetaddictsanonymous.org\/internet-and-technology-addiction\/social-media-addiction\/signs-of-facebook-addiction\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/internetaddictsanonymous.org\/"},{"@type":"ListItem","position":2,"name":"Signs of Internet and Technology Addiction","item":"https:\/\/internetaddictsanonymous.org\/internet-and-technology-addiction\/"},{"@type":"ListItem","position":3,"name":"Recovering from Social Media Addiction","item":"https:\/\/internetaddictsanonymous.org\/internet-and-technology-addiction\/social-media-addiction\/"},{"@type":"ListItem","position":4,"name":"Signs of Facebook Addiction"}]},{"@type":"WebSite","@id":"https:\/\/internetaddictsanonymous.org\/#website","url":"https:\/\/internetaddictsanonymous.org\/","name":"Dependentes de Internet e Tecnologia An\u00f4nimos","description":"Bolsa mundial de 12 passos para Internet e v\u00edcio em tecnologia","publisher":{"@id":"https:\/\/internetaddictsanonymous.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/internetaddictsanonymous.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/internetaddictsanonymous.org\/#organization","name":"Dependentes de Internet e Tecnologia An\u00f4nimos","url":"https:\/\/internetaddictsanonymous.org\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/internetaddictsanonymous.org\/#\/schema\/logo\/image\/","url":"https:\/\/internetaddictsanonymous.org\/wp-content\/uploads\/2023\/01\/cropped-ITAA-logo-480px.png","contentUrl":"https:\/\/internetaddictsanonymous.org\/wp-content\/uploads\/2023\/01\/cropped-ITAA-logo-480px.png","width":480,"height":480,"caption":"Internet and Technology Addicts Anonymous"},"image":{"@id":"https:\/\/internetaddictsanonymous.org\/#\/schema\/logo\/image\/"}}]}},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/P9Fwob-4Ze","_links":{"self":[{"href":"https:\/\/internetaddictsanonymous.org\/pt\/wp-json\/wp\/v2\/pages\/19172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/internetaddictsanonymous.org\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/internetaddictsanonymous.org\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/internetaddictsanonymous.org\/pt\/wp-json\/wp\/v2\/users\/35194289"}],"replies":[{"embeddable":true,"href":"https:\/\/internetaddictsanonymous.org\/pt\/wp-json\/wp\/v2\/comments?post=19172"}],"version-history":[{"count":6,"href":"https:\/\/internetaddictsanonymous.org\/pt\/wp-json\/wp\/v2\/pages\/19172\/revisions"}],"predecessor-version":[{"id":19623,"href":"https:\/\/internetaddictsanonymous.org\/pt\/wp-json\/wp\/v2\/pages\/19172\/revisions\/19623"}],"up":[{"embeddable":true,"href":"https:\/\/internetaddictsanonymous.org\/pt\/wp-json\/wp\/v2\/pages\/4446"}],"wp:attachment":[{"href":"https:\/\/internetaddictsanonymous.org\/pt\/wp-json\/wp\/v2\/media?parent=19172"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/internetaddictsanonymous.org\/pt\/wp-json\/wp\/v2\/tags?post=19172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}